{"id":6611,"date":"2024-04-30T15:11:00","date_gmt":"2024-04-30T20:11:00","guid":{"rendered":"https:\/\/lifefm.ec\/?p=6611"},"modified":"2024-04-30T15:11:00","modified_gmt":"2024-04-30T20:11:00","slug":"guatemala-emite-una-declaracion-de-emergencia-nacional-debido-a-un-brote-epidemico-de-dengue","status":"publish","type":"post","link":"https:\/\/lifefm.ec\/index.php\/2024\/04\/30\/guatemala-emite-una-declaracion-de-emergencia-nacional-debido-a-un-brote-epidemico-de-dengue\/","title":{"rendered":"GUATEMALA EMITE UNA DECLARACI\u00d3N DE EMERGENCIA NACIONAL DEBIDO A UN BROTE EPID\u00c9MICO DE DENGUE"},"content":{"rendered":"<blockquote><p>El a\u00f1o pasado, Guatemala registr\u00f3 118 muertes y aproximadamente 65,000 casos de dengue, estableciendo una preocupante realidad sanitaria en el pa\u00eds.<\/p><\/blockquote>\n<p>En respuesta a la creciente incidencia de casos de dengue, que ha resultado en nueve fallecimientos y m\u00e1s de 14,600 personas enfermas desde enero, Guatemala anunci\u00f3 este martes la declaraci\u00f3n de una emergencia sanitaria nacional. El Ministerio de Salud emiti\u00f3 un llamado a los organismos p\u00fablicos y privados del sector para coordinar acciones destinadas a prevenir brotes, incluyendo jornadas de fumigaci\u00f3n, y mantener una vigilancia constante con el objetivo de reducir la mortalidad.<\/p>\n<p>En marzo, el gobierno del presidente Bernardo Ar\u00e9valo emiti\u00f3 una alerta epidemiol\u00f3gica nacional, reconociendo el inicio de la temporada en la que aumenta la transmisi\u00f3n del dengue en el pa\u00eds. Esta enfermedad ha experimentado un notable incremento a nivel mundial en las \u00faltimas dos d\u00e9cadas, siendo Am\u00e9rica Latina la regi\u00f3n que concentra el 80% de los casos, seg\u00fan datos del ministerio guatemalteco.<\/p>\n<p>El a\u00f1o pasado, el dengue alcanz\u00f3 cifras alarmantes en Guatemala, con 118 fallecimientos y alrededor de 65,000 casos, superando el registro del a\u00f1o anterior. Esta enfermedad end\u00e9mica de las zonas tropicales se manifiesta con fiebres altas, dolores de cabeza, n\u00e1useas, v\u00f3mitos, dolor muscular y, en casos graves, hemorragias que pueden resultar letales.<\/p>\n<p>La Organizaci\u00f3n Mundial de la Salud (OMS) alert\u00f3 en abril de 2023 sobre la propagaci\u00f3n ampliada y m\u00e1s extensa de enfermedades transmitidas por mosquitos, como el dengue, debido al cambio clim\u00e1tico.<\/p>\n<p>&nbsp;<\/p>\n<p>F: El Universo<br \/>\n#Life #LifeNoticias #RadioLife995FM #InformativoLife #Babahoyo #ThiIsLife #SintonizaLaVida<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El a\u00f1o pasado, Guatemala registr\u00f3 118 muertes y aproximadamente 65,000 casos de dengue, estableciendo una preocupante realidad sanitaria en el pa\u00eds. En respuesta a la creciente incidencia de casos de dengue, que ha resultado en nueve fallecimientos y m\u00e1s de 14,600 personas enfermas desde enero, Guatemala anunci\u00f3 este martes la declaraci\u00f3n de una emergencia sanitaria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6612,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-6611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-mundo"],"_links":{"self":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/6611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/comments?post=6611"}],"version-history":[{"count":1,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/6611\/revisions"}],"predecessor-version":[{"id":6613,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/6611\/revisions\/6613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media\/6612"}],"wp:attachment":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media?parent=6611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/categories?post=6611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/tags?post=6611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}