{"id":6592,"date":"2024-04-30T14:04:40","date_gmt":"2024-04-30T19:04:40","guid":{"rendered":"https:\/\/lifefm.ec\/?p=6592"},"modified":"2024-04-30T14:04:40","modified_gmt":"2024-04-30T19:04:40","slug":"eduardo-pena-fmi-financiara-elaboracion-de-reforma-al-iees-y-su-difusion-a-la-ciudadania","status":"publish","type":"post","link":"https:\/\/lifefm.ec\/index.php\/2024\/04\/30\/eduardo-pena-fmi-financiara-elaboracion-de-reforma-al-iees-y-su-difusion-a-la-ciudadania\/","title":{"rendered":"EDUARDO PE\u00d1A: FMI FINANCIAR\u00c1 ELABORACI\u00d3N DE REFORMA AL IEES Y SU DIFUSI\u00d3N A LA CIUDADAN\u00cdA"},"content":{"rendered":"<blockquote><p>El Fondo Monetario Internacional (FMI) financiar\u00e1 la elaboraci\u00f3n y puesta en conocimiento de la ciudadan\u00eda de un proyecto de ley para darle sostenibilidad al sistema del Instituto Ecuatoriano de Seguridad Social (IESS). Adem\u00e1s de que este organismo internacional tendr\u00eda claro que la situaci\u00f3n del IESS es compleja por lo que ha pedido al Estado que cancele sus deudas con la entidad que buscar\u00e1 aumentar el n\u00famero de afiliados para subir la relaci\u00f3n entre afiliados y jubilados del actual 5 a 1 a 6 a 1.<\/p><\/blockquote>\n<p>Estos fueron varios de los anuncios que ha hecho en estos d\u00edas el presidente del Consejo Directivo del IESS, Eduardo Pe\u00f1a, quien explic\u00f3 que el proyecto de ley a\u00fan debe ser bien afinado y que debe ser conocido por la Asamblea Nacional.<\/p>\n<p>De todos modos, dio pistas de cu\u00e1les ser\u00edan las reformas estructurales. Por ejemplo, se buscar\u00eda promover que los afiliados se jubilen m\u00e1s tarde, pero con pensiones mayores. As\u00ed mencion\u00f3 que si un afiliado tiene 400 aportaciones podr\u00eda tener 80 % y si ha hecho 460 aportaciones 85 %, pero si llega a las 500 aportaciones podr\u00eda tener una pensi\u00f3n equivalente al 110 % del sueldo.<\/p>\n<p>Adicionalmente, mencion\u00f3 el tema del c\u00e1lculo de la pensi\u00f3n. Esta se hace ahora con base a los cinco mejores a\u00f1os de salarios, pero esto no estar\u00eda reflejando lo que en realidad aport\u00f3 el afiliado. Para Pe\u00f1a, el c\u00e1lculo deber\u00eda basarse en los 30 a\u00f1os de aportaciones.<\/p>\n<p>Este proyecto podr\u00eda tardar unos seis o siete meses en construirse y llevarlo a debate con la ciudadan\u00eda. Mientras tanto, se espera que el pr\u00f3ximo a\u00f1o haya un ambiente legislativo favorable para poderlo aprobar.<\/p>\n<p>Sobre el pago que debe hacer el Estado al IESS por la contribuci\u00f3n del 40 % a las pensiones ($ 2.390 millones solo este a\u00f1o), explic\u00f3 que el Gobierno s\u00ed est\u00e1 cumpliendo y que actualmente los bonos del Estado rinden un 9 %, es decir un porcentaje mayor que otro tipo de inversiones.<\/p>\n<p>El IESS tiene la meta de incrementar a sus afiliados en 70.000 al a\u00f1o. Para eso ha emprendido un proyecto de afiliaci\u00f3n temprana que permite la afiliaci\u00f3n de personas entre 15 a\u00f1os a 24 a\u00f1os. Estas tienen el beneficio de que se jubilan m\u00e1s j\u00f3venes y pueden acceder a pr\u00e9stamos hipotecarios. Al momento ha habido 2.600 nuevas afiliaciones. En la campa\u00f1a est\u00e1n participando 80 agentes que tienen cuotas m\u00ednimas a cumplir.<\/p>\n<p>F: El Universo<\/p>\n<p>#Life #LifeNoticias #RadioLife995FM #InformativoLife #Babahoyo #ThiIsLife #SintonizaLaVida<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Fondo Monetario Internacional (FMI) financiar\u00e1 la elaboraci\u00f3n y puesta en conocimiento de la ciudadan\u00eda de un proyecto de ley para darle sostenibilidad al sistema del Instituto Ecuatoriano de Seguridad Social (IESS). Adem\u00e1s de que este organismo internacional tendr\u00eda claro que la situaci\u00f3n del IESS es compleja por lo que ha pedido al Estado que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6598,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-6592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/6592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/comments?post=6592"}],"version-history":[{"count":1,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/6592\/revisions"}],"predecessor-version":[{"id":6599,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/6592\/revisions\/6599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media\/6598"}],"wp:attachment":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media?parent=6592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/categories?post=6592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/tags?post=6592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}