{"id":5871,"date":"2024-04-10T10:51:04","date_gmt":"2024-04-10T15:51:04","guid":{"rendered":"https:\/\/lifefm.ec\/?p=5871"},"modified":"2024-04-10T10:51:04","modified_gmt":"2024-04-10T15:51:04","slug":"entre-lagrimas-elizabeth-gutierrez-confirma-el-fin-de-su-matrimonio-con-william-levy-no-hablamos-el-mismo-lenguaje","status":"publish","type":"post","link":"https:\/\/lifefm.ec\/index.php\/2024\/04\/10\/entre-lagrimas-elizabeth-gutierrez-confirma-el-fin-de-su-matrimonio-con-william-levy-no-hablamos-el-mismo-lenguaje\/","title":{"rendered":"ENTRE L\u00c1GRIMAS ELIZABETH GUTI\u00c9RREZ CONFIRMA EL FIN DE SU MATRIMONIO CON WILLIAM LEVY: \u2018NO HABLAMOS EL MISMO LENGUAJE\u2019"},"content":{"rendered":"<blockquote>\n<p class=\"prose-text\">La actriz <b>Elizabeth Guti\u00e9rrez <\/b>no contuvo sus l\u00e1grimas cuando en una entrevista se refiri\u00f3 a <b>William Levy,<\/b> a quien describi\u00f3 como \u201cel amor de su vida\u201d. La pareja le puso fin a su matrimonio, y esta vez ser\u00eda definitivo.<\/p>\n<\/blockquote>\n<p class=\"prose-text\">La mexicana de 45 a\u00f1os y el actor cubano de 43 han atrevasado un duro a\u00f1o, marcados por una serie de rumores sobre su ruptura. En una entrevista con Hola!, confirm\u00f3 que en este momentos est\u00e1 separada del pap\u00e1 de sus hijos Kailey, de 14 y Christopher, de 18.<br \/>\n<b><\/b><\/p>\n<p class=\"prose-text\"><b>\u201cActualmente, no estamos juntos.<\/b> Creo que, por mi parte, <b>nunca fue por falta de amor, <\/b>simplemente creo que no soy la misma ni\u00f1a de hace 20 a\u00f1os que \u00e9l conoci\u00f3. O sea,<b> lo que queremos en este momento creo que es diferente\u201d, <\/b>expres\u00f3 en la entrevista.<\/p>\n<p class=\"prose-text\"><b>\u201cCreo que vamos por caminos diferentes, que no hablamos el mismo lenguaje, tal vez. O sea, son muchas cosas\u201d<\/b>, a\u00f1adi\u00f3.<\/p>\n<p class=\"prose-text\">La actriz no admiti\u00f3, ni neg\u00f3 que el cubano hay cometido infidelidad en la relaci\u00f3n. Sin embargo, prefiri\u00f3 destacar lo bueno de \u00e9l y enfatiz\u00f3 que solo ellos dos sab\u00eda la verdad, m\u00e1s all\u00e1 de lo que dec\u00edan los medios.<\/p>\n<p>\u201cLos dos luchamos por nuestra familia y por nuestra relaci\u00f3n.<b> Los dos dimos lo mejor que pudimos en nuestra relaci\u00f3n.<\/b>Estoy segura que \u00e9l tambi\u00e9n dio lo mejor de s\u00ed. Y <b>es una excelente persona y un tipo con un coraz\u00f3n enorme que siempre nos dio lo mejor como familia, <\/b>como proveedor. Pero creo que hab\u00eda muchas heridas que no se hab\u00edan sanado\u201d, sostuvo.<\/p>\n<p>F: EL UNIVERSO<\/p>\n<p>#Life #LifeNoticias #RadioLife995FM #InformativoLife #Babahoyo #ThiIsLife #SintonizaLaVida<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actriz Elizabeth Guti\u00e9rrez no contuvo sus l\u00e1grimas cuando en una entrevista se refiri\u00f3 a William Levy, a quien describi\u00f3 como \u201cel amor de su vida\u201d. La pareja le puso fin a su matrimonio, y esta vez ser\u00eda definitivo. La mexicana de 45 a\u00f1os y el actor cubano de 43 han atrevasado un duro a\u00f1o, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5875,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-5871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/5871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/comments?post=5871"}],"version-history":[{"count":1,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/5871\/revisions"}],"predecessor-version":[{"id":5881,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/5871\/revisions\/5881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media\/5875"}],"wp:attachment":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media?parent=5871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/categories?post=5871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/tags?post=5871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}