{"id":5795,"date":"2024-04-09T09:54:47","date_gmt":"2024-04-09T14:54:47","guid":{"rendered":"https:\/\/lifefm.ec\/?p=5795"},"modified":"2024-04-09T09:54:47","modified_gmt":"2024-04-09T14:54:47","slug":"el-rey-carlos-y-la-reina-camila-celebran-su-19o-aniversario-de-bodas","status":"publish","type":"post","link":"https:\/\/lifefm.ec\/index.php\/2024\/04\/09\/el-rey-carlos-y-la-reina-camila-celebran-su-19o-aniversario-de-bodas\/","title":{"rendered":"EL REY CARLOS Y LA REINA CAMILA CELEBRAN SU 19\u00ba ANIVERSARIO DE BODAS"},"content":{"rendered":"<blockquote>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">El rey Carlos, de 75 a\u00f1os, y la reina Camila, de 76, cumplieron hoy 19 a\u00f1os de matrimonio. <b>Los monarcas se casaron el 9 de abril de 2005, 35 a\u00f1os despu\u00e9s de su primer encuentro en 1970.<\/b><\/p>\n<\/blockquote>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">Carlos y Camila se conocieron por primera vez en un partido de polo en Windsor Great Park, un parque real, donde descubrieron que ambos amaban el polo y pasar al aire libre. Comenzaron a salir, pero el rey en ese entonces se marcha para servir en la Royal Navy durante ocho meses.<\/p>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">Cuando regresa en 1973, Camila est\u00e1 comprometida con Andrew Parker Bowles, quien se convertir\u00eda en su primer esposo y padre de sus dos hijos. Por su lado en 1981, <b>Carlos, de 31 a\u00f1os, empieza una relaci\u00f3n con Lady Diana Spencer, de 18. <\/b>Ese mismo a\u00f1o la pareja contrae matrimonio en la catedral de San Pablo. Entre los invitados se encontraba Camila.<\/p>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">Pero <b>en 1986, seg\u00fan la biograf\u00eda autorizada del rey, tiene una aventura con Camila. <\/b>Cerca de 5 a\u00f1os despu\u00e9s, \u00e9l se divorcia oficialmente de Diana, y en 1995 Camila se separa de su esposo.<\/p>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">Finalmente en el 2005, Carlos y Camila anuncian su compromiso y el 9 de abril se casan en una ceremonia civil con el pr\u00edncipe William como padrino. <b>La Reina no asiste a la boda, <\/b>pero s\u00ed asiste a la recepci\u00f3n posterior.<\/p>\n<p data-mrf-recirculation=\"Links article\">Este a\u00f1o, es probable que la pareja celebre en privado mientras el rey contin\u00faa recibiendo tratamiento contra el c\u00e1ncer desde que el pasado 5 de febrero compartieran la noticia de su diagn\u00f3stico.<\/p>\n<p data-mrf-recirculation=\"Links article\">\nF: EL UNIVERSO<\/p>\n<p>#Life #LifeNoticias #RadioLife995FM #InformativoLife #Babahoyo #ThiIsLife #SintonizaLaVida<\/p>\n<p data-mrf-recirculation=\"Links article\">\n","protected":false},"excerpt":{"rendered":"<p>El rey Carlos, de 75 a\u00f1os, y la reina Camila, de 76, cumplieron hoy 19 a\u00f1os de matrimonio. Los monarcas se casaron el 9 de abril de 2005, 35 a\u00f1os despu\u00e9s de su primer encuentro en 1970. Carlos y Camila se conocieron por primera vez en un partido de polo en Windsor Great Park, un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5799,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-5795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/5795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/comments?post=5795"}],"version-history":[{"count":1,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/5795\/revisions"}],"predecessor-version":[{"id":5803,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/5795\/revisions\/5803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media\/5799"}],"wp:attachment":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media?parent=5795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/categories?post=5795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/tags?post=5795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}