{"id":5765,"date":"2024-04-08T12:03:51","date_gmt":"2024-04-08T17:03:51","guid":{"rendered":"https:\/\/lifefm.ec\/?p=5765"},"modified":"2024-04-08T12:03:51","modified_gmt":"2024-04-08T17:03:51","slug":"mar-rendon-y-naiza-acompanaran-a-danna-paola-en-sus-shows-en-ecuador","status":"publish","type":"post","link":"https:\/\/lifefm.ec\/index.php\/2024\/04\/08\/mar-rendon-y-naiza-acompanaran-a-danna-paola-en-sus-shows-en-ecuador\/","title":{"rendered":"MAR REND\u00d3N Y NA\u00cdZA ACOMPA\u00d1AR\u00c1N A DANNA PAOLA EN SUS SHOWS EN ECUADOR"},"content":{"rendered":"<blockquote><p>Danna Paola llega a Ecuador con su gira \u00abDanna Live!\u00bb para ofrecer dos espect\u00e1culos \u00fanicos en Guayaquil y Quito, marcando su primera vez en el pa\u00eds.<\/p><\/blockquote>\n<p>La aclamada actriz y cantante, reconocida por \u00e9xitos como \u00abMala Fama\u00bb y \u00abOye Pablo\u00bb, compartir\u00e1 el escenario con dos destacadas artistas guayaquile\u00f1as, Mar Rend\u00f3n y Na\u00edza, como representantes de la escena musical local.<\/p>\n<p>El jueves 2 de mayo, el primer concierto tendr\u00e1 lugar en Arena Top Media de Quito a las 20:00 horas, seguido por el segundo el s\u00e1bado 4 de mayo en el Palacio de Cristal de Guayaquil a las 19:30 horas. Los asistentes podr\u00e1n disfrutar de una experiencia inolvidable junto a estas talentosas artistas.<\/p>\n<p>Las entradas para los conciertos de Danna Paola en Ecuador ya est\u00e1n disponibles. Los precios de los boletos en Quito y Guayaquil son los siguientes: general preventa $26,50, VIP preventa $56,50, Mala Fama Box $101,50 y Dannas VIP $251,50.<\/p>\n<p>Adem\u00e1s de su paso por Ecuador, la nominada al Grammy Latino continuar\u00e1 su gira con presentaciones en diversas ciudades como Austin, Monterrey, Bogot\u00e1, Lima, Santiago de Chile, Montevideo, Sao Paulo y Valle del Napa.<\/p>\n<p>&nbsp;<\/p>\n<p>F: El Universo<\/p>\n<p>#Life #LifeNoticias #RadioLife995FM #InformativoLife #Babahoyo #ThiIsLife #SintonizaLaVida<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Danna Paola llega a Ecuador con su gira \u00abDanna Live!\u00bb para ofrecer dos espect\u00e1culos \u00fanicos en Guayaquil y Quito, marcando su primera vez en el pa\u00eds. La aclamada actriz y cantante, reconocida por \u00e9xitos como \u00abMala Fama\u00bb y \u00abOye Pablo\u00bb, compartir\u00e1 el escenario con dos destacadas artistas guayaquile\u00f1as, Mar Rend\u00f3n y Na\u00edza, como representantes de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5766,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-5765","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/5765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/comments?post=5765"}],"version-history":[{"count":1,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/5765\/revisions"}],"predecessor-version":[{"id":5767,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/5765\/revisions\/5767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media\/5766"}],"wp:attachment":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media?parent=5765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/categories?post=5765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/tags?post=5765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}