{"id":13191,"date":"2026-01-28T10:36:31","date_gmt":"2026-01-28T15:36:31","guid":{"rendered":"https:\/\/lifefm.ec\/?p=13191"},"modified":"2026-01-28T10:36:31","modified_gmt":"2026-01-28T15:36:31","slug":"tramo-ferroviario-el-tambo-coyoctor-se-reactiva-tras-casi-una-decada","status":"publish","type":"post","link":"https:\/\/lifefm.ec\/index.php\/2026\/01\/28\/tramo-ferroviario-el-tambo-coyoctor-se-reactiva-tras-casi-una-decada\/","title":{"rendered":"TRAMO FERROVIARIO EL TAMBO-COYOCTOR SE REACTIVA TRAS CASI UNA D\u00c9CADA"},"content":{"rendered":"<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">El convenio para la reactivaci\u00f3n, administraci\u00f3n y operaci\u00f3n del tramo ferroviario El Tambo-Coyoctor se firm\u00f3 entre el Ministerio de Infraestructura y Transporte (MIT), la Empresa P\u00fablica Ferrocarriles del Ecuador en Liquidaci\u00f3n y el Municipio de El Tambo (Ca\u00f1ar).<\/p>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">El documento suscrito se da en el marco de un convenio espec\u00edfico de delegaci\u00f3n de competencias concurrentes y gesti\u00f3n compartida.<\/p>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">Con esta herramienta se apunta a reactivar este tramo con fines tur\u00edsticos, patrimoniales y para desarrollo econ\u00f3mico local.<\/p>\n<div class=\"inline-element\">\n<div><\/div>\n<\/div>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">Esta l\u00ednea ferroviaria se paraliz\u00f3 cerca de una d\u00e9cada, mencion\u00f3 el alcalde de El Tambo, Alonso Castillo.<\/p>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">La autoridad remarc\u00f3 que esta reactivaci\u00f3n tendr\u00e1 su impacto en la generaci\u00f3n de empleo, en el fortalecimiento del turismo comunitario y en la dinamizaci\u00f3n de la econom\u00eda.<\/p>\n<div class=\"inline-element\">\n<div>\n<div id=\"active-campaing-form-marcador\"><\/div>\n<\/div>\n<\/div>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">El subsecretario de Transporte Terrestre y Ferroviario, Geovanny Moreano, dijo que la ruta patrimonial no solo dinamizar\u00e1 la econom\u00eda local sino que adem\u00e1s \u201cunir\u00e1 a la gente\u201d.<\/p>\n<div class=\"inline-element\">\n<div>\n<div id=\"active-campaing-form\"><\/div>\n<\/div>\n<\/div>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">El convenio tiene una vigencia de cinco a\u00f1os, contempla la rehabilitaci\u00f3n y mantenimiento de la v\u00eda f\u00e9rrea, la operaci\u00f3n tur\u00edstica, la recuperaci\u00f3n de estaciones y bienes inmuebles ferroviarios, as\u00ed como la integraci\u00f3n de las comunidades locales y la puesta en valor del patrimonio cultural del cant\u00f3n.<\/p>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">La cartera de Infraestructura ejerce la rector\u00eda, control y supervisi\u00f3n t\u00e9cnica del proyecto. Mientras, el Municipio de El Tambo asumir\u00e1 la administraci\u00f3n, operaci\u00f3n y financiamiento de la ruta, reinvirtiendo el 100 % de los ingresos generados en su mantenimiento y fortalecimiento.<\/p>\n<p class=\"prose-text\" data-mrf-recirculation=\"Links article\">La ruta tiene tres kil\u00f3metros de longitud. En un recorrido realizado luego de la firma del convenio se constataron da\u00f1os por el abandono en el que estuvo la infraestructura. El Municipio ejecutar\u00e1 las acciones necesarias para la recuperaci\u00f3n de la v\u00eda, con seguimiento t\u00e9cnico y apoyo del MIT.<\/p>\n<p data-mrf-recirculation=\"Links article\">\n<p data-mrf-recirculation=\"Links article\">F: El Universo<\/p>\n<p data-mrf-recirculation=\"Links article\">Imagen Referencial<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El convenio para la reactivaci\u00f3n, administraci\u00f3n y operaci\u00f3n del tramo ferroviario El Tambo-Coyoctor se firm\u00f3 entre el Ministerio de Infraestructura y Transporte (MIT), la Empresa P\u00fablica Ferrocarriles del Ecuador en Liquidaci\u00f3n y el Municipio de El Tambo (Ca\u00f1ar). El documento suscrito se da en el marco de un convenio espec\u00edfico de delegaci\u00f3n de competencias concurrentes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13192,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-13191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"_links":{"self":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/13191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/comments?post=13191"}],"version-history":[{"count":1,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/13191\/revisions"}],"predecessor-version":[{"id":13193,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/13191\/revisions\/13193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media\/13192"}],"wp:attachment":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media?parent=13191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/categories?post=13191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/tags?post=13191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}