{"id":13002,"date":"2025-06-16T16:17:00","date_gmt":"2025-06-16T21:17:00","guid":{"rendered":"https:\/\/lifefm.ec\/?p=13002"},"modified":"2025-06-16T16:17:00","modified_gmt":"2025-06-16T21:17:00","slug":"la-venta-de-telefonica-a-millicom-en-ecuador-solo-se-concretara-si-el-estado-renueva-su-concesion","status":"publish","type":"post","link":"https:\/\/lifefm.ec\/index.php\/2025\/06\/16\/la-venta-de-telefonica-a-millicom-en-ecuador-solo-se-concretara-si-el-estado-renueva-su-concesion\/","title":{"rendered":"LA VENTA DE TELEF\u00d3NICA A MILLICOM EN ECUADOR SOLO SE CONCRETAR\u00c1 SI EL ESTADO RENUEVA SU CONCESI\u00d3N"},"content":{"rendered":"<p>La renovaci\u00f3n de la concesi\u00f3n del servicio de telefon\u00eda m\u00f3vil a Otecel, filial de la multinacional espa\u00f1ola Telef\u00f3nica en Ecuador, es una de las condiciones de \u00abcierre\u00bb para la venta de sus operaciones en Ecuador, incluidas sus marcas Movistar y Tuenti, a la compa\u00f1\u00eda Millicom<\/p>\n<p>Telef\u00f3nica Hispam, el holding que agrupa las operaciones de Telef\u00f3nica en Am\u00e9rica Latina, anunci\u00f3 el 13 de junio que alcanz\u00f3 un acuerdo con Milicom Spain para la venta de Otecel (Telef\u00f3nica Ecuador). La transacci\u00f3n est\u00e1 valorada en USD 380 millones.<\/p>\n<p>\u00bfQu\u00e9 es Millicom, la empresa que comprar\u00e1 Movistar en Ecuador y que maneja la marca Tigo?<br \/>\nMillicom Spain es filial de la multinacional Millicom, con sede principal en Luxemburgo, que cotiza en la bolsa de Nueva York, y es uno de los principales proveedores de servicios de telefon\u00eda fija y m\u00f3vil en Am\u00e9rica Latina. Su principal marca de telefon\u00eda m\u00f3vil es Tigo, que tiene presencia en pa\u00edses como Bolivia, Colombia, Costa Rica y Honduras.<\/p>\n<p>\u00abEl cierre de la transacci\u00f3n est\u00e1 sujeto tambi\u00e9n a determinadas condiciones de cierre, incluyendo la obtenci\u00f3n de las pertinentes aprobaciones regulatorias\u00bb, dice el comunicado enviado por Telef\u00f3nica a sus inversionistas en el mercado de valores de Espa\u00f1a.<\/p>\n<p>PRIMICIAS conoci\u00f3 que una de esas \u00abcondiciones de cierre\u00bb para que se concrete la venta es que Telef\u00f3nica finalmente cierre la negociaci\u00f3n con el Estado ecuatoriano para la renovaci\u00f3n de la concesi\u00f3n del servicio de telefon\u00eda m\u00f3vil por 15 a\u00f1os m\u00e1s.<\/p>\n<p>Telef\u00f3nica es actualmente el segundo operador m\u00f3vil del pa\u00eds, con una participaci\u00f3n de mercado cercana al 28% y una base de aproximadamente 5 millones de clientes al cierre de marzo de 2025.<\/p>\n<p>Estas reuniones deb\u00edan durar 120 d\u00edas, como parte de un proceso de negociaci\u00f3n que, en todas sus fases, preve\u00eda un plazo de dos a\u00f1os, tiempo que empez\u00f3 a correr en agosto de 2021,\u00a0con la disposici\u00f3n del inicio de las negociaciones para las dos operadoras: Otecel (Telef\u00f3nica) y el Consorcio Ecuatoriano de Telecomunicaciones (Conecel), filial de la multinacional mexicana Claro.<\/p>\n<p>Es decir, de acuerdo con los plazos establecidos por la Agencia de Regulaci\u00f3n y Control de las Telecomunicaciones (Arcotel), los dos a\u00f1os debieron cumplirse en agosto de 2023. Pero, a la fecha, las negociaciones ya llevan casi dos a\u00f1os de retraso.<\/p>\n<p>Lo anterior debido a que el proceso de negociaci\u00f3n ha sido suspendido en reiteradas ocasiones, lo que ha obligado al Estado a otorgar pr\u00f3rrogas del contrato actual a Telef\u00f3nica, que venc\u00eda el 30 de noviembre de 2023. Al momento, la empresa est\u00e1 operando en Ecuador con la s\u00e9ptima pr\u00f3rroga a su contrato, otorgada el pasado 15 de mayo.<\/p>\n<p>Seg\u00fan la Resoluci\u00f3n Arcotel-2025-0079, el plazo de vencimiento de esta extensi\u00f3n es el pr\u00f3ximo 15 de julio, es decir, hasta fecha deber\u00eda firmarse el pr\u00f3ximo contrato para la renovaci\u00f3n de la concesi\u00f3n.<\/p>\n<p>F: Primicias<\/p>\n<p>Imagen Referencial<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La renovaci\u00f3n de la concesi\u00f3n del servicio de telefon\u00eda m\u00f3vil a Otecel, filial de la multinacional espa\u00f1ola Telef\u00f3nica en Ecuador, es una de las condiciones de \u00abcierre\u00bb para la venta de sus operaciones en Ecuador, incluidas sus marcas Movistar y Tuenti, a la compa\u00f1\u00eda Millicom Telef\u00f3nica Hispam, el holding que agrupa las operaciones de Telef\u00f3nica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13003,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-13002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/13002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/comments?post=13002"}],"version-history":[{"count":1,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/13002\/revisions"}],"predecessor-version":[{"id":13004,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/13002\/revisions\/13004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media\/13003"}],"wp:attachment":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media?parent=13002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/categories?post=13002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/tags?post=13002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}