{"id":11551,"date":"2024-11-11T12:29:21","date_gmt":"2024-11-11T17:29:21","guid":{"rendered":"https:\/\/lifefm.ec\/?p=11551"},"modified":"2024-11-11T12:29:21","modified_gmt":"2024-11-11T17:29:21","slug":"que-dice-la-polemica-nueva-cancion-de-karol-g-hasta-el-alcalde-de-quito-pabel-munoz-e-instituciones-publicas-de-colombia-se-quejaron","status":"publish","type":"post","link":"https:\/\/lifefm.ec\/index.php\/2024\/11\/11\/que-dice-la-polemica-nueva-cancion-de-karol-g-hasta-el-alcalde-de-quito-pabel-munoz-e-instituciones-publicas-de-colombia-se-quejaron\/","title":{"rendered":"\u00bfQu\u00e9 dice la pol\u00e9mica nueva canci\u00f3n de Karol G? Hasta el alcalde de Quito, Pabel Mu\u00f1oz, e instituciones p\u00fablicas de Colombia se quejaron"},"content":{"rendered":"<blockquote><p>La principal cr\u00edtica de la nueva canci\u00f3n de Karol G \u2018+57\u2019 es que sexualiza a menores de edad. La pol\u00e9mica es mundial y hasta el alcalde de Quito, Pabel Mu\u00f1oz, reproch\u00f3 la letra. Tambi\u00e9n las instituciones de bienestar familiar rechazaron la canci\u00f3n \u00bfqu\u00e9 dice?.<\/p><\/blockquote>\n<p><!--more--><\/p>\n<p>La nueva canci\u00f3n de Karol G (+57) ha sido blanco de cr\u00edticas, no solo musicales, sino de instituciones sociales y pol\u00edticas. Lo que naci\u00f3 como una colaboraci\u00f3n ic\u00f3nica entre Karol G;Maluma; J Balvin; Feid, Blessd; Ryan Castro y el artista emergente DF, es ahora\u00a0blanco de rechazo.<\/p>\n<p>&nbsp;<\/p>\n<p>Ni el alcalde de Quito, Pabel Mu\u00f1oz, aguant\u00f3 las ganas de oponerse a la letra. Incluso,\u00a0el Instituto Colombiano de Bienestar Familiar\u00a0envi\u00f3 un mensaje en contra de la canci\u00f3n. Mientras que la revista Rolling Stone en Espa\u00f1ol acab\u00f3 con la pieza musical.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00bfQu\u00e9 dice la pol\u00e9mica letra de la nueva canci\u00f3n de Karol G?<\/p>\n<p>&nbsp;<\/p>\n<p>La principal pol\u00e9mica se enfoca en la estrofa donde Maluma y Feid hacen referencia a que las mujeres desde los 14 a\u00f1os, cuando todav\u00eda son ni\u00f1as, se pueden ver de una manera f\u00edsica sexualmete llamativa y hasta pueden ir a discotecas.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cUna mamacita desde los fourteen (14 a\u00f1os), entra a la disco y se le siente el kit\u201d,\u00a0dice letra.<\/p>\n<p>&nbsp;<\/p>\n<p>Bienestar Familiar de Colombia dijo: \u00a0\u201cRechazo a la canci\u00f3n \u2018+57\u2032 y lamentamos que talentos de nuestro pa\u00eds promuevan contenidos que fomentan el sexualismo a temprana edad. Es momento de dejar de normalizar m\u00fasica que no contribuye al crecimiento positivo de los adolescentes. #57\u2033.<\/p>\n<p>Por su lado, la revistaRolling Stone en Espa\u00f1ol dijo: \u201cEs grav\u00edsimo que, a estas alturas de la conversaci\u00f3n sobre la narcocultura y la cultura de la violaci\u00f3n, se sigan tocando libremente temas como la sexualizaci\u00f3n a menores en las canciones\u201d,<\/p>\n<p>Mientras que el Alcalde de Quito dijo: \u201cLa \u00faltima producci\u00f3n de las \u201cestrellas\u201d del reguet\u00f3n (+57) es un desperdicio. Las y los adolescentes son un grupo de atenci\u00f3n prioritaria; sin embargo, los cantantes, hacen una letra que es una oda a todas las amenazas que enfrentan. Hay que pensar en los efectos no previstos de lo que se difunde masivamente. Tal vez ciertas novelas de TV no lo quisieron, pero generaron una narco-cultura. \u00bfPueden ciertas letras, como la de +57, alentar los riesgos que enfrentan las y los adolescentes, cada vez a edades m\u00e1s tempranas?\u201d, escribi\u00f3 en su cuenta de X. (AVV)<\/p>\n<p>F: LA HORA<\/p>\n<p>#RadioLife #LifeFM #LifeNoticias #LifeEntretenimiento #995<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La principal cr\u00edtica de la nueva canci\u00f3n de Karol G \u2018+57\u2019 es que sexualiza a menores de edad. La pol\u00e9mica es mundial y hasta el alcalde de Quito, Pabel Mu\u00f1oz, reproch\u00f3 la letra. Tambi\u00e9n las instituciones de bienestar familiar rechazaron la canci\u00f3n \u00bfqu\u00e9 dice?.<\/p>\n","protected":false},"author":1,"featured_media":11552,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-11551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"_links":{"self":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/11551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/comments?post=11551"}],"version-history":[{"count":1,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/11551\/revisions"}],"predecessor-version":[{"id":11553,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/posts\/11551\/revisions\/11553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media\/11552"}],"wp:attachment":[{"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/media?parent=11551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/categories?post=11551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lifefm.ec\/index.php\/wp-json\/wp\/v2\/tags?post=11551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}